{"id":1394,"date":"2016-02-12T10:27:50","date_gmt":"2016-02-12T09:27:50","guid":{"rendered":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg"},"modified":"2016-02-12T10:27:50","modified_gmt":"2016-02-12T09:27:50","slug":"publika1","status":"inherit","type":"attachment","link":"http:\/\/tmp.warp-poligon.info\/si\/otvoritev-razstave-ob-polstoletni-zgodovini-borstnikovega-srecanja\/publika1\/","title":{"rendered":"publika1"},"author":3,"comment_status":"closed","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"og:url\" content=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5152\" \/>\n\t<meta property=\"og:image:height\" content=\"3864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\",\"name\":\"publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"isPartOf\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\"},\"datePublished\":\"2016-02-12T09:27:50+00:00\",\"dateModified\":\"2016-02-12T09:27:50+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/tmp.warp-poligon.info\/si\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otvoritev razstave ob polstoletni zgodovini Bor\u0161tnikovega sre\u010danja\",\"item\":\"http:\/\/tmp.warp-poligon.info\/si\/otvoritev-razstave-ob-polstoletni-zgodovini-borstnikovega-srecanja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"publika1\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/\",\"name\":\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","og_locale":"sl_SI","og_type":"article","og_title":"publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","og_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","og_site_name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","og_image":[{"width":5152,"height":3864,"url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","name":"publika1 | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","isPartOf":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/#website"},"datePublished":"2016-02-12T09:27:50+00:00","dateModified":"2016-02-12T09:27:50+00:00","breadcrumb":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/tmp.warp-poligon.info\/si\/"},{"@type":"ListItem","position":2,"name":"Otvoritev razstave ob polstoletni zgodovini Bor\u0161tnikovega sre\u010danja","item":"http:\/\/tmp.warp-poligon.info\/si\/otvoritev-razstave-ob-polstoletni-zgodovini-borstnikovega-srecanja\/"},{"@type":"ListItem","position":3,"name":"publika1"}]},{"@type":"WebSite","@id":"http:\/\/tmp.warp-poligon.info\/si\/#website","url":"http:\/\/tmp.warp-poligon.info\/si\/","name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":5152,"height":3864,"file":"2016\/02\/publika1.jpg","sizes":{"thumbnail":{"file":"publika1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-150x150.jpg"},"medium":{"file":"publika1-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-300x225.jpg"},"large":{"file":"publika1-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1-1024x768.jpg"},"full":{"file":"publika1.jpg","width":5152,"height":3864,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg"}},"image_meta":{"aperture":3.3,"credit":"","camera":"DSC-W830","caption":"","created_timestamp":1454612872,"copyright":"","focal_length":"4.5","iso":"400","shutter_speed":"0.033333333333333","title":""}},"post":1364,"source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2016\/02\/publika1.jpg","_links":{"self":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media\/1394"}],"collection":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/comments?post=1394"}]}}