{"id":2556,"date":"2017-12-04T13:44:55","date_gmt":"2017-12-04T12:44:55","guid":{"rendered":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg"},"modified":"2017-12-08T16:14:52","modified_gmt":"2017-12-08T15:14:52","slug":"marko_luka_zeljko","status":"inherit","type":"attachment","link":"http:\/\/tmp.warp-poligon.info\/si\/2550-2\/marko_luka_zeljko\/","title":{"rendered":"MARKO_LUKA_ZELJKO"},"author":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"og:description\" content=\"Pobudnika Alpinisti\u010dnih \u010detrtkov in avtorja razstave: \u017deljko \u017darak (prvi desno) iz zalo\u017eni\u0161ke hi\u0161e Libricon, ki je specializirana za planinsko in potopisno literaturo in Marko Vukovi\u0107 (prvi levo) iz iniciative Plezati je treba, z Luko Krajncem.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-08T15:14:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4608\" \/>\n\t<meta property=\"og:image:height\" content=\"3456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\",\"name\":\"MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"isPartOf\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\"},\"datePublished\":\"2017-12-04T12:44:55+00:00\",\"dateModified\":\"2017-12-08T15:14:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/tmp.warp-poligon.info\/si\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alpinisti\u010dni \u010detrtek z odli\u010dnim Lukom Krajncem\",\"item\":\"http:\/\/tmp.warp-poligon.info\/si\/2550-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MARKO_LUKA_ZELJKO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/\",\"name\":\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","og_locale":"sl_SI","og_type":"article","og_title":"MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","og_description":"Pobudnika Alpinisti\u010dnih \u010detrtkov in avtorja razstave: \u017deljko \u017darak (prvi desno) iz zalo\u017eni\u0161ke hi\u0161e Libricon, ki je specializirana za planinsko in potopisno literaturo in Marko Vukovi\u0107 (prvi levo) iz iniciative Plezati je treba, z Luko Krajncem.","og_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","og_site_name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","article_modified_time":"2017-12-08T15:14:52+00:00","og_image":[{"width":4608,"height":3456,"url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","name":"MARKO_LUKA_ZELJKO | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","isPartOf":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/#website"},"datePublished":"2017-12-04T12:44:55+00:00","dateModified":"2017-12-08T15:14:52+00:00","breadcrumb":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/tmp.warp-poligon.info\/si\/"},{"@type":"ListItem","position":2,"name":"Alpinisti\u010dni \u010detrtek z odli\u010dnim Lukom Krajncem","item":"http:\/\/tmp.warp-poligon.info\/si\/2550-2\/"},{"@type":"ListItem","position":3,"name":"MARKO_LUKA_ZELJKO"}]},{"@type":"WebSite","@id":"http:\/\/tmp.warp-poligon.info\/si\/#website","url":"http:\/\/tmp.warp-poligon.info\/si\/","name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-200x150.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-400x300.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-600x450.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-768x576.jpg 768w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-800x600.jpg 800w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-1024x768.jpg 1024w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-1200x900.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Pobudnika Alpinisti\u010dnih \u010detrtkov in avtorja razstave: \u017deljko \u017darak (prvi desno) iz zalo\u017eni\u0161ke hi\u0161e Libricon, ki je specializirana za planinsko in potopisno literaturo in Marko Vukovi\u0107 (prvi levo) iz iniciative Plezati je treba, z Luko Krajncem.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4608,"height":3456,"file":"2017\/11\/MARKO_LUKA_ZELJKO.jpg","sizes":{"thumbnail":{"file":"MARKO_LUKA_ZELJKO-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-150x150.jpg"},"medium":{"file":"MARKO_LUKA_ZELJKO-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-300x225.jpg"},"medium_large":{"file":"MARKO_LUKA_ZELJKO-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-768x576.jpg"},"large":{"file":"MARKO_LUKA_ZELJKO-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-1024x768.jpg"},"magazin-thumb":{"file":"MARKO_LUKA_ZELJKO-150x212.jpg","width":150,"height":212,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-150x212.jpg"},"magazin-thumb-mini":{"file":"MARKO_LUKA_ZELJKO-100x141.jpg","width":100,"height":141,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-100x141.jpg"},"portfolio-full":{"file":"MARKO_LUKA_ZELJKO-940x400.jpg","width":940,"height":400,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-940x400.jpg"},"portfolio-one":{"file":"MARKO_LUKA_ZELJKO-540x272.jpg","width":540,"height":272,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-540x272.jpg"},"portfolio-two":{"file":"MARKO_LUKA_ZELJKO-460x295.jpg","width":460,"height":295,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-460x295.jpg"},"portfolio-three":{"file":"MARKO_LUKA_ZELJKO-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-300x214.jpg"},"portfolio-five":{"file":"MARKO_LUKA_ZELJKO-177x142.jpg","width":177,"height":142,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-177x142.jpg"},"blog-large":{"file":"MARKO_LUKA_ZELJKO-669x272.jpg","width":669,"height":272,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-669x272.jpg"},"blog-medium":{"file":"MARKO_LUKA_ZELJKO-320x202.jpg","width":320,"height":202,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-320x202.jpg"},"recent-posts":{"file":"MARKO_LUKA_ZELJKO-700x441.jpg","width":700,"height":441,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-700x441.jpg"},"recent-works-thumbnail":{"file":"MARKO_LUKA_ZELJKO-66x66.jpg","width":66,"height":66,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-66x66.jpg"},"fusion-200":{"file":"MARKO_LUKA_ZELJKO-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-200x150.jpg"},"fusion-400":{"file":"MARKO_LUKA_ZELJKO-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-400x300.jpg"},"fusion-600":{"file":"MARKO_LUKA_ZELJKO-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-600x450.jpg"},"fusion-800":{"file":"MARKO_LUKA_ZELJKO-800x600.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-800x600.jpg"},"fusion-1200":{"file":"MARKO_LUKA_ZELJKO-1200x900.jpg","width":1200,"height":900,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO-1200x900.jpg"},"full":{"file":"MARKO_LUKA_ZELJKO.jpg","width":4608,"height":3456,"mime_type":"image\/jpeg","source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg"}},"image_meta":{"aperture":"3.3","credit":"","camera":"DSC-W690","caption":"","created_timestamp":"1484076452","copyright":"","focal_length":"4.45","iso":"500","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":2550,"source_url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2017\/11\/MARKO_LUKA_ZELJKO.jpg","_links":{"self":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media\/2556"}],"collection":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/comments?post=2556"}]}}