{"id":3126,"date":"2018-06-16T15:31:27","date_gmt":"2018-06-16T13:31:27","guid":{"rendered":"http:\/\/tmp.warp-poligon.info\/si\/?p=3126"},"modified":"2018-06-18T15:42:13","modified_gmt":"2018-06-18T13:42:13","slug":"slovenski-pesnik-na-festivalu-vrazova-ljubica","status":"publish","type":"post","link":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/","title":{"rendered":"Slovenski pesnik na festivalu Vrazova Ljubica"},"content":{"rendered":"<p>Samobor \u2013 Na 29. Festivalu hrva\u0161ke ljubezenske poezije, ki vsako leto poteka v \u010dast Vrazove neusli\u0161ane ljubezni Julijane Ljubice Cantilly, je tudi letos sodeloval pesnik iz Slovenije. Valter \u010cu\u010dkovi\u010d iz Maribora je v dru\u017ebi \u0161tevilnih pesnikov in obiskovalcev prebral svojo pesem v brajici, ki jo je napisal posebej za to prilo\u017enost. (akm)<\/p>\n<p style=\"text-align: center\">Neznanka<br \/>\n1<br \/>\nNocoj uga\u0161a odhojena samota,<br \/>\nker prihaja\u0161 k meni, ko rojijo<br \/>\nzvezde iz plamenov in kresni\u010dijo<br \/>\nnebo na \u017eametu zaobljene \u010drnine.<br \/>\nVe\u010der rojeva sanje po zaplatah<br \/>\nhrepenenja, ki jih tkejo medonosne<br \/>\nvile z biblijo ljubezni med koleni.<br \/>\nPotopljeni dan se zgo\u0161\u010da v o\u010desu<br \/>\nsve\u010de na sti\u010di\u0161\u010du najinih sledi<br \/>\nv etru, kamor sedajo metulji.<br \/>\n2<br \/>\nPrihaja\u0161 k meni skozi vitice<br \/>\n\u010drtovja na rumenkastih straneh<br \/>\nbo\u017eanske partiture iz zakladnice<br \/>\nnebes, ko svet polagoma zamira.<br \/>\nNo\u010d prepletem z melodijo lune<br \/>\nin zari\u0161em cvet narcise, kjer poljub<br \/>\nrazpira ustne za po\u017eirek ognja,<br \/>\nko prisede\u0161 k meni, ne da bi zares<br \/>\nbila, ne da bi zares ljubila<br \/>\nz \u017earom \u010dastihlepne Ptolemejke.<br \/>\n3<br \/>\nMrak se tanj\u0161a proti zori jutra<br \/>\nin slednji\u010d sem razbil utvaro<br \/>\nz vinom v kristalu \u010drne kupe.<br \/>\nNi te in ne pride\u0161, zato obesim<br \/>\nro\u017enati privid na zid trpljenja<br \/>\nv moji galeriji nanizanega \u010dasa.<br \/>\nPogrezam se nazaj v jek samote<br \/>\nin po kapljah bri\u0161em neznankino<br \/>\ntelo iz misli, da lahko svobodno<br \/>\nodlebdim med note vinske rapsodije.<\/p>\n<p style=\"text-align: center\">Valter \u010cu\u010dkovi\u010d<\/p>\n<p style=\"text-align: left\">Foto: akm<\/p>\n<p style=\"text-align: left\">Ve\u010d v Novem odmevu 66.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-3126 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2.jpg'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-3131\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2-200x267.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2-225x300.jpg 225w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2-400x533.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2-600x800.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/5-2.jpg 700w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3131'>\n\t\t\t\tValter \u010cu\u010dkovi\u010d ob grobu Julijane Ljubice Cantilly pri cerkvi sv. Anastazije.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2.jpg'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-3132\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2-200x267.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2-225x300.jpg 225w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2-400x533.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2-600x800.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/6-2.jpg 700w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3132'>\n\t\t\t\tGrob Julijane Ljubice Cantilly.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-3127\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1-200x150.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1-400x300.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1-600x450.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/1-1.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3127'>\n\t\t\t\tRecitiranje Valterja \u010cu\u010dkovi\u010da; park pri Samoborskem muzeju.\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-3129\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2-200x150.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2-400x300.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2-600x450.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/3-2.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3129'>\n\t\t\t\tPesem Neznanka v brajici.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2-200x150.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2-400x300.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2-600x450.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/4-2.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-3128\" srcset=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2-200x150.jpg 200w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2-300x225.jpg 300w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2-400x300.jpg 400w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2-600x450.jpg 600w, http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/2-2.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-3128'>\n\t\t\t\t\u010clanice SSNM MZ so skupaj z Valterjem \u010cu\u010dkovi\u010dem in njegovo spremljevalko Darinko polo\u017eile cvietje na Vrazov spomenik.\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Samobor \u2013 Na 29. Festivalu hrva\u0161ke ljubezenske poezije, ki vsako leto poteka v \u010dast Vrazove neusli\u0161ane ljubezni Julijane Ljubice Cantilly, je tudi letos sodeloval pesnik iz Slovenije. Valter \u010cu\u010dkovi\u010d iz Maribora je v dru\u017ebi \u0161tevilnih pesnikov in obiskovalcev prebral svojo pesem v brajici, ki jo je napisal posebej za to prilo\u017enost. (akm) Neznanka 1 Nocoj [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"og:description\" content=\"Samobor \u2013 Na 29. Festivalu hrva\u0161ke ljubezenske poezije, ki vsako leto poteka v \u010dast Vrazove neusli\u0161ane ljubezni Julijane Ljubice Cantilly, je tudi letos sodeloval pesnik iz Slovenije. Valter \u010cu\u010dkovi\u010d iz Maribora je v dru\u017ebi \u0161tevilnih pesnikov in obiskovalcev prebral svojo pesem v brajici, ki jo je napisal posebej za to prilo\u017enost. (akm) Neznanka 1 Nocoj [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/\" \/>\n<meta property=\"og:site_name\" content=\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-16T13:31:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-18T13:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/logo-Vrazova-Ljubica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agata\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agata\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/\",\"name\":\"Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"isPartOf\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\"},\"datePublished\":\"2018-06-16T13:31:27+00:00\",\"dateModified\":\"2018-06-18T13:42:13+00:00\",\"author\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/a34ecc40aa73e6dd78780facef777d32\"},\"breadcrumb\":{\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/tmp.warp-poligon.info\/si\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slovenski pesnik na festivalu Vrazova Ljubica\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#website\",\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/\",\"name\":\"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/a34ecc40aa73e6dd78780facef777d32\",\"name\":\"agata\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/42c070b2dbf14a48e0639733f946c907?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/42c070b2dbf14a48e0639733f946c907?s=96&d=mm&r=g\",\"caption\":\"agata\"},\"url\":\"http:\/\/tmp.warp-poligon.info\/si\/author\/agata\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/","og_locale":"sl_SI","og_type":"article","og_title":"Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","og_description":"Samobor \u2013 Na 29. Festivalu hrva\u0161ke ljubezenske poezije, ki vsako leto poteka v \u010dast Vrazove neusli\u0161ane ljubezni Julijane Ljubice Cantilly, je tudi letos sodeloval pesnik iz Slovenije. Valter \u010cu\u010dkovi\u010d iz Maribora je v dru\u017ebi \u0161tevilnih pesnikov in obiskovalcev prebral svojo pesem v brajici, ki jo je napisal posebej za to prilo\u017enost. (akm) Neznanka 1 Nocoj [&hellip;]","og_url":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/","og_site_name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","article_published_time":"2018-06-16T13:31:27+00:00","article_modified_time":"2018-06-18T13:42:13+00:00","og_image":[{"width":300,"height":114,"url":"http:\/\/tmp.warp-poligon.info\/si\/wp-content\/uploads\/sites\/2\/2018\/06\/logo-Vrazova-Ljubica.jpg","type":"image\/jpeg"}],"author":"agata","twitter_misc":{"Written by":"agata","Est. reading time":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/","url":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/","name":"Slovenski pesnik na festivalu Vrazova Ljubica | Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","isPartOf":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/#website"},"datePublished":"2018-06-16T13:31:27+00:00","dateModified":"2018-06-18T13:42:13+00:00","author":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/a34ecc40aa73e6dd78780facef777d32"},"breadcrumb":{"@id":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/tmp.warp-poligon.info\/si\/slovenski-pesnik-na-festivalu-vrazova-ljubica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/tmp.warp-poligon.info\/si\/"},{"@type":"ListItem","position":2,"name":"Slovenski pesnik na festivalu Vrazova Ljubica"}]},{"@type":"WebSite","@id":"http:\/\/tmp.warp-poligon.info\/si\/#website","url":"http:\/\/tmp.warp-poligon.info\/si\/","name":"Slovenski dom in Svet slovenske nacionalne manj\u0161ine Mesta Zagreb","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/tmp.warp-poligon.info\/si\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"},{"@type":"Person","@id":"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/a34ecc40aa73e6dd78780facef777d32","name":"agata","image":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"http:\/\/tmp.warp-poligon.info\/si\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/42c070b2dbf14a48e0639733f946c907?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/42c070b2dbf14a48e0639733f946c907?s=96&d=mm&r=g","caption":"agata"},"url":"http:\/\/tmp.warp-poligon.info\/si\/author\/agata\/"}]}},"_links":{"self":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/posts\/3126"}],"collection":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/comments?post=3126"}],"version-history":[{"count":1,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/posts\/3126\/revisions"}],"predecessor-version":[{"id":3134,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/posts\/3126\/revisions\/3134"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media\/3133"}],"wp:attachment":[{"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/media?parent=3126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/categories?post=3126"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/tmp.warp-poligon.info\/si\/wp-json\/wp\/v2\/tags?post=3126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}